{"id":7130,"date":"2015-11-11T13:33:57","date_gmt":"2015-11-11T12:33:57","guid":{"rendered":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg"},"modified":"2015-11-11T13:42:16","modified_gmt":"2015-11-11T12:42:16","slug":"4546353565_c84a51ae67_z","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.com\/blog\/2015\/11\/walk-italy\/4546353565_c84a51ae67_z\/#main","title":{"rendered":"4546353565_c84a51ae67_z"},"author":33,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4546353565_c84a51ae67_z - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4546353565_c84a51ae67_z - Ecobnb\" \/>\n<meta property=\"og:description\" content=\"Photo by Francesco Moscone via Flickr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecobnb\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-11T12:42:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ecobnb\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4546353565_c84a51ae67_z - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"4546353565_c84a51ae67_z - Ecobnb","og_description":"Photo by Francesco Moscone via Flickr","og_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/ecobnb","article_modified_time":"2015-11-11T12:42:16+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ecobnb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg","name":"4546353565_c84a51ae67_z - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.com\/blog\/#website"},"datePublished":"2015-11-11T12:33:57+00:00","dateModified":"2015-11-11T12:42:16+00:00","breadcrumb":{"@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"2016 &#8211; Year of Walk: 10 itineraries in Italy for this year","item":"https:\/\/ecobnb.com\/blog\/2015\/11\/walk-italy\/"},{"@type":"ListItem","position":2,"name":"4546353565_c84a51ae67_z"}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.com\/blog\/#website","url":"https:\/\/ecobnb.com\/blog\/","name":"Ecobnb","description":"Find sustainable accommodation","publisher":{"@id":"https:\/\/ecobnb.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecobnb.com\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecobnb","https:\/\/twitter.com\/ecobnb"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg'><img width=\"536\" height=\"357\" src=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-536x357.jpg\" class=\"attachment-medium size-medium\" alt=\"Orfento Valley\" srcset=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-536x357.jpg 536w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-344x229.jpg 344w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg 640w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Photo by Francesco Moscone via Flickr<\/p>\n"},"alt_text":"Orfento Valley","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":426,"file":"2015\/11\/4546353565_c84a51ae67_z.jpg","sizes":{"thumbnail":{"file":"4546353565_c84a51ae67_z-270x200.jpg","width":270,"height":200,"filesize":26490,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-270x200.jpg"},"medium":{"file":"4546353565_c84a51ae67_z-536x357.jpg","width":536,"height":357,"filesize":87861,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-536x357.jpg"},"half":{"file":"4546353565_c84a51ae67_z-570x320.jpg","width":570,"height":320,"filesize":83365,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-570x320.jpg"},"portrait":{"file":"4546353565_c84a51ae67_z-344x229.jpg","width":344,"height":229,"filesize":38303,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z-344x229.jpg"},"full":{"file":"4546353565_c84a51ae67_z.jpg","width":640,"height":426,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"filesize":349042},"post":7104,"source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/11\/4546353565_c84a51ae67_z.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media\/7130"}],"collection":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/users\/33"}]}}