{"id":5054,"date":"2015-01-05T20:29:49","date_gmt":"2015-01-05T19:29:49","guid":{"rendered":"http:\/\/blog.italygreentravel.com\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg"},"modified":"2015-01-05T20:31:43","modified_gmt":"2015-01-05T19:31:43","slug":"altopiano-di-campo-imperatore-piccolo-tibet-abruzzo-cincinnato","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.com\/blog\/2014\/12\/snowshoes\/altopiano-di-campo-imperatore-piccolo-tibet-abruzzo-cincinnato\/#main","title":{"rendered":"Abruzzo"},"author":3,"comment_status":"closed","ping_status":"open","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abruzzo - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abruzzo - Ecobnb\" \/>\n<meta property=\"og:description\" content=\"Altopiano di Campo Imperatore, snow covered, better known as &quot;Piccolo Tibet&quot;, ph. by Abruzzo Cincinnato, via flickr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecobnb\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-05T19:31:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ecobnb\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abruzzo - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Abruzzo - Ecobnb","og_description":"Altopiano di Campo Imperatore, snow covered, better known as \"Piccolo Tibet\", ph. by Abruzzo Cincinnato, via flickr","og_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/ecobnb","article_modified_time":"2015-01-05T19:31:43+00:00","og_image":[{"width":800,"height":508,"url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ecobnb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","name":"Abruzzo - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.com\/blog\/#website"},"datePublished":"2015-01-05T19:29:49+00:00","dateModified":"2015-01-05T19:31:43+00:00","breadcrumb":{"@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"10 trips with snowshoes, from Alps to Abruzzo, to celebrate the beginning of the new year","item":"https:\/\/ecobnb.com\/blog\/2014\/12\/snowshoes\/"},{"@type":"ListItem","position":2,"name":"Abruzzo"}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.com\/blog\/#website","url":"https:\/\/ecobnb.com\/blog\/","name":"Ecobnb","description":"Find sustainable accommodation","publisher":{"@id":"https:\/\/ecobnb.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecobnb.com\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecobnb","https:\/\/twitter.com\/ecobnb"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg'><img width=\"536\" height=\"340\" src=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-536x340.jpg\" class=\"attachment-medium size-medium\" alt=\"Altopiano di Campo Imperatore, known as &quot;Piccolo Tibet&quot;, Abruzzo, Italy\" srcset=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-536x340.jpg 536w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-344x218.jpg 344w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg 800w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Altopiano di Campo Imperatore, snow covered, better known as &#8220;Piccolo Tibet&#8221;,  ph. by Abruzzo Cincinnato, via flickr<\/p>\n"},"alt_text":"Altopiano di Campo Imperatore, known as \"Piccolo Tibet\", Abruzzo, Italy","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":508,"file":"2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","sizes":{"thumbnail":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-270x200.jpg","width":270,"height":200,"filesize":9867,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-270x200.jpg"},"medium":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-536x340.jpg","width":536,"height":340,"filesize":26046,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-536x340.jpg"},"large":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-800x490.jpg","width":800,"height":490,"filesize":51944,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-800x490.jpg"},"wide":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-800x490.jpg","width":800,"height":490,"filesize":51944,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-800x490.jpg"},"half":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-570x320.jpg","width":570,"height":320,"filesize":27242,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-570x320.jpg"},"portrait":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-344x218.jpg","width":344,"height":218,"filesize":12825,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato-344x218.jpg"},"full":{"file":"Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","width":800,"height":508,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg"}},"image_meta":{"aperture":3.2000000000000002,"credit":"","camera":"NIKON D50","caption":"","created_timestamp":1198950268,"copyright":"","focal_length":"75","iso":0,"shutter_speed":"0.00625","title":"","orientation":1},"filesize":46340},"post":5042,"source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2015\/01\/Altopiano-di-Campo-Imperatore-Piccolo-Tibet-Abruzzo-Cincinnato.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media\/5054"}],"collection":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/users\/3"}]}}