{"id":4928,"date":"2014-12-19T23:23:56","date_gmt":"2014-12-19T22:23:56","guid":{"rendered":"http:\/\/blog.italygreentravel.com\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg"},"modified":"2014-12-19T23:24:34","modified_gmt":"2014-12-19T22:24:34","slug":"sunset-on-winter-solstice-days-photography-by-stephen-little-via-flickr","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.com\/blog\/2014\/12\/winter-solstice\/sunset-on-winter-solstice-days-photography-by-stephen-little-via-flickr\/#main","title":{"rendered":"Sunset on winter solstice days photography by Stephen Little via Flickr"},"author":13,"comment_status":"closed","ping_status":"open","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sunset on winter solstice days photography by Stephen Little via Flickr - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sunset on winter solstice days photography by Stephen Little via Flickr - Ecobnb\" \/>\n<meta property=\"og:description\" content=\"Sunset on winter solstice days photography by Stephen Little via Flickr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecobnb\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-19T22:24:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ecobnb\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sunset on winter solstice days photography by Stephen Little via Flickr - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Sunset on winter solstice days photography by Stephen Little via Flickr - Ecobnb","og_description":"Sunset on winter solstice days photography by Stephen Little via Flickr","og_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/ecobnb","article_modified_time":"2014-12-19T22:24:34+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ecobnb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","name":"Sunset on winter solstice days photography by Stephen Little via Flickr - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.com\/blog\/#website"},"datePublished":"2014-12-19T22:23:56+00:00","dateModified":"2014-12-19T22:24:34+00:00","breadcrumb":{"@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Winter solstice: it\u2019s cold out there!","item":"https:\/\/ecobnb.com\/blog\/2014\/12\/winter-solstice\/"},{"@type":"ListItem","position":2,"name":"Sunset on winter solstice days photography by Stephen Little via Flickr"}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.com\/blog\/#website","url":"https:\/\/ecobnb.com\/blog\/","name":"Ecobnb","description":"Find sustainable accommodation","publisher":{"@id":"https:\/\/ecobnb.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecobnb.com\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecobnb","https:\/\/twitter.com\/ecobnb"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg\" class=\"attachment-medium size-medium\" alt=\"Sunset\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Sunset on winter solstice days photography by Stephen Little via Flickr<\/p>\n"},"alt_text":"Sunset","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":300,"height":300,"file":"2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","sizes":{"thumbnail":{"file":"Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr-270x200.jpg","width":270,"height":200,"filesize":8922,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr-270x200.jpg"},"full":{"file":"Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"filesize":10576},"post":4923,"source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2014\/12\/Sunset-on-winter-solstice-days-photography-by-Stephen-Little-via-Flickr.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media\/4928"}],"collection":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/users\/13"}]}}