{"id":21756,"date":"2018-12-17T23:00:26","date_gmt":"2018-12-17T22:00:26","guid":{"rendered":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png"},"modified":"2018-12-17T23:00:36","modified_gmt":"2018-12-17T22:00:36","slug":"ecobnb-trova-il-tuo-alloggio-eco-sostenibile-20-e1542095120965-2","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.com\/blog\/ecobnb-trova-il-tuo-alloggio-eco-sostenibile-20-e1542095120965-2\/","title":{"rendered":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e1542095120965"},"author":84,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e1542095120965 - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e1542095120965 - Ecobnb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecobnb\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-17T22:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1197\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ecobnb\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e1542095120965 - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e1542095120965 - Ecobnb","og_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/ecobnb","article_modified_time":"2018-12-17T22:00:36+00:00","og_image":[{"width":1197,"height":466,"url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ecobnb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","name":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e1542095120965 - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.com\/blog\/#website"},"datePublished":"2018-12-17T22:00:26+00:00","dateModified":"2018-12-17T22:00:36+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png"]}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.com\/blog\/#website","url":"https:\/\/ecobnb.com\/blog\/","name":"Ecobnb","description":"Find sustainable accommodation","publisher":{"@id":"https:\/\/ecobnb.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecobnb.com\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecobnb","https:\/\/twitter.com\/ecobnb"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png'><img width=\"536\" height=\"209\" src=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-536x209.png\" class=\"attachment-medium size-medium\" alt=\"digital gift card\" srcset=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-536x209.png 536w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-344x134.png 344w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png 1197w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"digital gift card","media_type":"image","mime_type":"image\/png","media_details":{"width":1197,"height":466,"file":"2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","sizes":{"thumbnail":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-270x200.png","width":270,"height":200,"filesize":74780,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-270x200.png"},"medium":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-536x209.png","width":536,"height":209,"filesize":152673,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-536x209.png"},"large":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-870x466.png","width":870,"height":466,"filesize":427193,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-870x466.png"},"wide":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-1170x466.png","width":1170,"height":466,"filesize":589854,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-1170x466.png"},"half":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-570x320.png","width":570,"height":320,"filesize":223099,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-570x320.png"},"portrait":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-344x134.png","width":344,"height":134,"filesize":66459,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651-344x134.png"},"full":{"file":"Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","width":1197,"height":466,"mime_type":"image\/png","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"filesize":605017},"post":null,"source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2018\/12\/Ecobnb-Trova-il-tuo-alloggio-Eco-Sostenibile-20-e15420951209651.png","_links":{"self":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media\/21756"}],"collection":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/users\/84"}]}}