{"id":14071,"date":"2017-05-22T18:09:07","date_gmt":"2017-05-22T16:09:07","guid":{"rendered":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg"},"modified":"2017-05-22T18:09:28","modified_gmt":"2017-05-22T16:09:28","slug":"agriturismo_la_piantata_arlena-di-castro_viterbo-870x490","status":"inherit","type":"attachment","link":"https:\/\/ecobnb.com\/blog\/agriturismo_la_piantata_arlena-di-castro_viterbo-870x490\/","title":{"rendered":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870&#215;490"},"author":33,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490 - Ecobnb<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490 - Ecobnb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ecobnb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecobnb\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-22T16:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ecobnb\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490 - Ecobnb","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490 - Ecobnb","og_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","og_site_name":"Ecobnb","article_publisher":"https:\/\/www.facebook.com\/ecobnb","article_modified_time":"2017-05-22T16:09:28+00:00","og_image":[{"width":870,"height":490,"url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ecobnb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","name":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490 - Ecobnb","isPartOf":{"@id":"https:\/\/ecobnb.com\/blog\/#website"},"datePublished":"2017-05-22T16:09:07+00:00","dateModified":"2017-05-22T16:09:28+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg"]}]},{"@type":"WebSite","@id":"https:\/\/ecobnb.com\/blog\/#website","url":"https:\/\/ecobnb.com\/blog\/","name":"Ecobnb","description":"Find sustainable accommodation","publisher":{"@id":"https:\/\/ecobnb.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecobnb.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecobnb.com\/blog\/#organization","name":"Ecobnb","url":"https:\/\/ecobnb.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","contentUrl":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2016\/03\/logo_transparent_512x512.png","width":512,"height":512,"caption":"Ecobnb"},"image":{"@id":"https:\/\/ecobnb.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecobnb","https:\/\/twitter.com\/ecobnb"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg'><img width=\"536\" height=\"302\" src=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-536x302.jpg\" class=\"attachment-medium size-medium\" alt=\"How to improve your advertisement on Ecobnb\" srcset=\"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-536x302.jpg 536w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg 870w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-570x320.jpg 570w, https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-344x194.jpg 344w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"How to improve your advertisement on Ecobnb","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":870,"height":490,"file":"2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","sizes":{"thumbnail":{"file":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-270x200.jpg","width":270,"height":200,"filesize":24429,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-270x200.jpg"},"medium":{"file":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-536x302.jpg","width":536,"height":302,"filesize":65235,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-536x302.jpg"},"wide":{"file":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-870x490.jpg","width":870,"height":490,"filesize":170236,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-870x490.jpg"},"half":{"file":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-570x320.jpg","width":570,"height":320,"filesize":72454,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-570x320.jpg"},"portrait":{"file":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-344x194.jpg","width":344,"height":194,"filesize":30549,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490-344x194.jpg"},"full":{"file":"Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","width":870,"height":490,"mime_type":"image\/jpeg","source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"filesize":173314},"post":null,"source_url":"https:\/\/ecobnb.com\/blog\/app\/uploads\/sites\/3\/2017\/05\/Agriturismo_La_Piantata_Arlena-di-Castro_Viterbo-870x490.jpg","_links":{"self":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media\/14071"}],"collection":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ecobnb.com\/blog\/wp-json\/wp\/v2\/users\/33"}]}}